{"id":33,"date":"2006-10-22T21:47:40","date_gmt":"2006-10-22T20:47:40","guid":{"rendered":"http:\/\/www.lechatbotte.org\/myrtille\/?p=33"},"modified":"2007-05-08T15:21:48","modified_gmt":"2007-05-08T14:21:48","slug":"raviolis-a-litalienne","status":"publish","type":"post","link":"https:\/\/lechatbotte.org\/myrtille\/2006\/10\/raviolis-a-litalienne\/","title":{"rendered":"Raviolis \u00e0\u00a0 l&#8217;italienne"},"content":{"rendered":"<p>Vous pouvez trouver la recette de base de raviolis ici (<a href=\"https:\/\/chatbotte.canalblog.com\/archives\/2006\/10\/19\/2944211.html\">clic<\/a>).<\/p>\n<p><strong>Raviolis \u00e0\u00a0 l&#8217;italienne<\/strong><br \/>\n<a href=\"https:\/\/lechatbotte.org\/myrtille\/?p=31\">p\u00e2te pour 2 personnes (200 gr de farine, 2 oeufs)<\/a><br \/>\n<u>Farce<\/u><br \/>\n1 cs huile<br \/>\n1 oignon hach\u00e9 finement<br \/>\n1 gousse d&#8217;ail<br \/>\n1 petite carotte coup\u00e9e en julienne<br \/>\n200 gr de hach\u00e9 de veau<br \/>\n20 gr de mie \u00e9miett\u00e9<br \/>\nparmesan \u00e0\u00a0 volont\u00e9<br \/>\n1\/4 de cc noix de muscade<br \/>\nsel et poivre<br \/>\n<u>Sauce tomate<\/u><br \/>\nboite de pur\u00e9e de tomates<br \/>\noignon hach\u00e9<br \/>\nsel et poivre<br \/>\nthym<\/p>\n<p>1 Faire revenir dans l&#8217;huile les l\u00e9gumes et l&#8217;ail. Rajouter la viande hach\u00e9e et laisser cuire lentement en \u00e9crasant bien la viande avec une fourchette.<\/p>\n<p>2 Rajouter le parmesan et la mie de pain, la muscade, sel et poivre. M\u00e9langer. Donner quelques coups de mixer, mais grossi\u00e8rement, sinon cela devient une p\u00e2te trop homog\u00e8ne.<\/p>\n<p>3 \u00e0\u2030taler la p\u00e2te et fourrer les raviolis. Laisser s\u00e9cher (la recette dit qq heures, mais je les ai laiss\u00e9 s\u00e9cher 30 minutes)<\/p>\n<p>4 Hacher finement l&#8217;oignon pour la sauce, rajouter la pur\u00e9e de tomates, poivre, sel, et thym. Laisser cuire une dizaines de minutes. Rajouter le reste de farce s&#8217;il y en a.<\/p>\n<p>5 Cuire les raviolis 3 minutes dans de l&#8217;eau bouillante, jusqu&#8217;\u00e0\u00a0 ce qu&#8217;ils flottent.<\/p>\n<p>6 Servir.<\/p>\n<p><strong>Source<\/strong> : adapt\u00e9 de <a href=\"https:\/\/ww.menara.ma\/Infos\/includes\/detail.asp?article_id=1944&amp;categorie=&amp;lmodule=Femmes\">Ravioli \u00e0\u00a0 l&#8217;italienne<\/a><br \/>\n<strong>Fdx<\/strong> : <a href=\"wp-content\/uploads\/2007\/05\/7658453.fdx\">raviolisitalienne<\/a><br \/>\n<strong>Bilan<\/strong> : 4\/5 Anne-Sophie, 3\/5 par l&#8217;Alchemist. Les raviolis \u00e9taient d\u00e9licieux. C&#8217;est une bonne recette facile, m\u00eame si faire ses raviolis soi-m\u00eame reste une activit\u00e9 qui prend du temps. Pas de photos, nous avions si faim que nous y avons pens\u00e9 trop tard.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous pouvez trouver la recette de base de raviolis ici (clic). Raviolis \u00e0\u00a0 l&#8217;italienne p\u00e2te pour 2 personnes (200 gr de farine, 2 oeufs) Farce 1 cs huile 1 oignon hach\u00e9 finement 1 gousse d&#8217;ail 1 petite carotte coup\u00e9e en julienne 200 gr de hach\u00e9 de veau 20 gr de mie \u00e9miett\u00e9 parmesan \u00e0\u00a0 volont\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-33","post","type-post","status-publish","format-standard","hentry","category-pates"],"_links":{"self":[{"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/posts\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":0,"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"wp:attachment":[{"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lechatbotte.org\/myrtille\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}